{"id":2873,"date":"2013-08-29T13:55:10","date_gmt":"2013-08-29T11:55:10","guid":{"rendered":"http:\/\/couven-museum.de\/?post_type=tribe_events&#038;p=2873"},"modified":"2013-12-23T18:36:07","modified_gmt":"2013-12-23T17:36:07","slug":"hausfuhrung-12-2","status":"publish","type":"tribe_events","link":"https:\/\/couven-museum.de\/en\/event\/hausfuhrung-12-2\/","title":{"rendered":"Hausf\u00fchrung"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>\u00d6ffentliche Hausf\u00fchrung durchs Couven-Museum mit Georg Tilger<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_lmt_disableupdate":"","_lmt_disable":"","_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[20],"class_list":["post-2873","tribe_events","type-tribe_events","status-publish","hentry","tribe_events_cat-fuehrungen-en","cat_fuehrungen-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hausf\u00fchrung - Couven Museum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/couven-museum.de\/en\/event\/hausfuhrung-12-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hausf\u00fchrung - Couven Museum\" \/>\n<meta property=\"og:description\" content=\"\u00d6ffentliche Hausf\u00fchrung durchs Couven-Museum mit Georg Tilger\" \/>\n<meta property=\"og:url\" content=\"https:\/\/couven-museum.de\/en\/event\/hausfuhrung-12-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Couven Museum\" \/>\n<meta property=\"article:modified_time\" content=\"2013-12-23T17:36:07+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/couven-museum.de\\\/en\\\/event\\\/hausfuhrung-12-2\\\/\",\"url\":\"https:\\\/\\\/couven-museum.de\\\/en\\\/event\\\/hausfuhrung-12-2\\\/\",\"name\":\"Hausf\u00fchrung - Couven Museum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/couven-museum.de\\\/#website\"},\"datePublished\":\"2013-08-29T11:55:10+00:00\",\"dateModified\":\"2013-12-23T17:36:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/couven-museum.de\\\/en\\\/event\\\/hausfuhrung-12-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/couven-museum.de\\\/en\\\/event\\\/hausfuhrung-12-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/couven-museum.de\\\/en\\\/event\\\/hausfuhrung-12-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/couven-museum.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/couven-museum.de\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hausf\u00fchrung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/couven-museum.de\\\/#website\",\"url\":\"https:\\\/\\\/couven-museum.de\\\/\",\"name\":\"Couven Museum\",\"description\":\"Couven-Museum Aachen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/couven-museum.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hausf\u00fchrung - Couven Museum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/couven-museum.de\/en\/event\/hausfuhrung-12-2\/","og_locale":"en_US","og_type":"article","og_title":"Hausf\u00fchrung - Couven Museum","og_description":"\u00d6ffentliche Hausf\u00fchrung durchs Couven-Museum mit Georg Tilger","og_url":"https:\/\/couven-museum.de\/en\/event\/hausfuhrung-12-2\/","og_site_name":"Couven Museum","article_modified_time":"2013-12-23T17:36:07+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/couven-museum.de\/en\/event\/hausfuhrung-12-2\/","url":"https:\/\/couven-museum.de\/en\/event\/hausfuhrung-12-2\/","name":"Hausf\u00fchrung - Couven Museum","isPartOf":{"@id":"https:\/\/couven-museum.de\/#website"},"datePublished":"2013-08-29T11:55:10+00:00","dateModified":"2013-12-23T17:36:07+00:00","breadcrumb":{"@id":"https:\/\/couven-museum.de\/en\/event\/hausfuhrung-12-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/couven-museum.de\/en\/event\/hausfuhrung-12-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/couven-museum.de\/en\/event\/hausfuhrung-12-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/couven-museum.de\/en\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/couven-museum.de\/events\/"},{"@type":"ListItem","position":3,"name":"Hausf\u00fchrung"}]},{"@type":"WebSite","@id":"https:\/\/couven-museum.de\/#website","url":"https:\/\/couven-museum.de\/","name":"Couven Museum","description":"Couven-Museum Aachen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/couven-museum.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/couven-museum.de\/en\/wp-json\/wp\/v2\/tribe_events\/2873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/couven-museum.de\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/couven-museum.de\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/couven-museum.de\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/couven-museum.de\/en\/wp-json\/wp\/v2\/tribe_events\/2873\/revisions"}],"wp:attachment":[{"href":"https:\/\/couven-museum.de\/en\/wp-json\/wp\/v2\/media?parent=2873"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/couven-museum.de\/en\/wp-json\/wp\/v2\/tags?post=2873"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/couven-museum.de\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=2873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}