{"id":11880,"date":"2019-09-05T16:45:10","date_gmt":"2019-09-05T14:45:10","guid":{"rendered":"https:\/\/couven-museum.de\/musee\/"},"modified":"2026-03-28T18:42:26","modified_gmt":"2026-03-28T17:42:26","slug":"musee","status":"publish","type":"page","link":"https:\/\/couven-museum.de\/fr\/musee\/","title":{"rendered":"Mus\u00e9e"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"11880\" class=\"elementor elementor-11880 elementor-5770\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-61276b27 elementor-section-content-middle elementor-section-height-min-height elementor-hidden-phone elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"61276b27\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_offset&quot;:125,&quot;sticky_on&quot;:[&quot;desktop&quot;],&quot;animation&quot;:&quot;none&quot;,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3c3675ba\" data-id=\"3c3675ba\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f706665 elementor-nav-menu--dropdown-none navigation ecs-toggle-align-left ecs-nav-layout-horizontal e--pointer-underline e--animation-fade elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"7f706665\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Men\u00fc\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-underline e--animation-fade\">\n\t\t\t\t<ul id=\"menu-1-7f706665\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-12089\"><a href=\"https:\/\/couven-museum.de\/fr\/musee\/#haus\" class=\"elementor-item elementor-item-anchor\">La maison<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-12090\"><a href=\"https:\/\/couven-museum.de\/fr\/musee\/#sammlung\" class=\"elementor-item elementor-item-anchor\">La collection<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-7f706665\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-12089\"><a href=\"https:\/\/couven-museum.de\/fr\/musee\/#haus\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">La maison<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-12090\"><a href=\"https:\/\/couven-museum.de\/fr\/musee\/#sammlung\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">La collection<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7f791ed3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7f791ed3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5a73ff09\" data-id=\"5a73ff09\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7410f563 elementor-widget elementor-widget-menu-anchor\" data-id=\"7410f563\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"haus\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62ff57cd elementor-widget elementor-widget-heading\" data-id=\"62ff57cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">LA MAISON<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-61b4eb2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"61b4eb2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-023afc2\" data-id=\"023afc2\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d633ad elementor-widget elementor-widget-spacer\" data-id=\"0d633ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e237d43\" data-id=\"e237d43\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-63a3e7b elementor-widget elementor-widget-text-editor\" data-id=\"63a3e7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>De la maison Coebergh au mus\u00e9e d\u2019aujourd\u2019hui<\/h3>\n<p><\/p>\n<p><b>L\u2019art de vivre aux XVIIIe et XIXe si\u00e8cles<\/b><\/p>\n<p><\/p>\n<p>\u00c0 partir de 1662, le pharmacien Adam Coebergh fit construire la maison situ\u00e9e sur le H\u00fchnermarkt, o\u00f9 il installa la pharmacie de l\u2019Aigle. Apr\u00e8s l\u2019acquisition du b\u00e2timent par Andreas Monheim en 1783, celui-ci le fit transformer trois ans plus tard par l\u2019architecte Jakob Couven. Apr\u00e8s la Seconde Guerre mondiale, en 1951, la ville d\u2019Aix-la-Chapelle acheta la maison \u00e0 la famille Quadflieg. En 1958, le mus\u00e9e Couven y fut inaugur\u00e9.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f54865a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f54865a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a101d3c\" data-id=\"a101d3c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d09f9e elementor-widget elementor-widget-menu-anchor\" data-id=\"6d09f9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"sammlung\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-701a9a49 elementor-widget elementor-widget-heading\" data-id=\"701a9a49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">LA COLLECTION<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6fc37e3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6fc37e3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-196c34c\" data-id=\"196c34c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cb88da4 elementor-widget elementor-widget-shortcode\" data-id=\"cb88da4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><\/div><div class=\"couven-grid lcp row\">\n    <div class=\"col-lg-4 col-md-6 col-12 couven-grid-item couven-teaser\">\n        <a href=\"https:\/\/couven-museum.de\/fr\/musee\/le-salon-de-musique\/\">\n        <div class=\"inner\">\n            <div class=\"grid-item-image\" style=\"background-image: url(https:\/\/couven-museum.de\/wp-content\/uploads\/2026\/03\/landschaftszimmer-couven-museum-460x363.jpg)\">\n            <\/div>\n\n            <div class=\"grid-item-content\">\n                <h3>Le salon de musique<\/h3>\n                <div>Au XIXe si\u00e8cle, outre l\u2019\u00e9ducation humaniste, la ma\u00eetrise de plusieurs langues et la connaissance de la litt\u00e9rature, de l\u2019art et du th\u00e9\u00e2tre, la musique faisait \u00e9galement partie du canon \u00e9ducatif des classes bourgeoises.<\/div>\n            <\/div>\n        <\/div>\n        <\/a>\n    <\/div>\n    <div class=\"col-lg-4 col-md-6 col-12 couven-grid-item couven-teaser\">\n        <a href=\"https:\/\/couven-museum.de\/fr\/musee\/cour-interieure\/\">\n        <div class=\"inner\">\n            <div class=\"grid-item-image\" style=\"background-image: url(https:\/\/couven-museum.de\/wp-content\/uploads\/2026\/03\/innenhof-couven-museum-460x363.jpg)\">\n            <\/div>\n\n            <div class=\"grid-item-content\">\n                <h3>Cour int\u00e9rieure<\/h3>\n                <div>Der Hof verbindet Haupt- und Hinterhaus miteinander. Der Brunnen an der Brandmauer zum benachbarten Haus hat eine Marmor-Einfassung aus dem sp\u00e4ten 18. Jahrhundert. Auf dem Becken sind drei Halbmonde zu erkennen, das Wappen der Familie Monheim. <\/div>\n            <\/div>\n        <\/div>\n        <\/a>\n    <\/div>\n    <div class=\"col-lg-4 col-md-6 col-12 couven-grid-item couven-teaser\">\n        <a href=\"https:\/\/couven-museum.de\/fr\/musee\/salon-donnant-sur-la-cour-interieure\/\">\n        <div class=\"inner\">\n            <div class=\"grid-item-image\" style=\"background-image: url(https:\/\/couven-museum.de\/wp-content\/uploads\/2026\/03\/hofzimmer-couven-museum-1-460x363.jpg)\">\n            <\/div>\n\n            <div class=\"grid-item-content\">\n                <h3>Salon donnant sur la cour int\u00e9rieure<\/h3>\n                <div>Les salles du Couven Museum sont meubl\u00e9es dans des styles allant du rococo au style Empire napol\u00e9onien, jusqu\u2019au Biedermeier. Le salon donnant sur la cour int\u00e9rieure est largement am\u00e9nag\u00e9 dans le style rococo. La chemin\u00e9e, avec sa riche ornementation anim\u00e9e, en est un bel exemple.<\/div>\n            <\/div>\n        <\/div>\n        <\/a>\n    <\/div>\n    <div class=\"col-lg-4 col-md-6 col-12 couven-grid-item couven-teaser\">\n        <a href=\"https:\/\/couven-museum.de\/fr\/musee\/salon-avec-cheminee\/\">\n        <div class=\"inner\">\n            <div class=\"grid-item-image\" style=\"background-image: url(https:\/\/couven-museum.de\/wp-content\/uploads\/2026\/03\/kaminzimmer-couven-museum-aachen-460x428.jpg)\">\n            <\/div>\n\n            <div class=\"grid-item-content\">\n                <h3>Salon avec chemin\u00e9e<\/h3>\n                <div>Salon avec chemin\u00e9e C\u2019est le stucateur italien Pietro Nicolo Gagini qui con\u00e7ut en 1778 la magnifique chemin\u00e9e pour lamaison de campagne Drimborn \u00e0 c\u00f4t\u00e9 d\u2019Aix-la-Chapelle, maison qui fut d\u00e9truite pendant [&hellip;]<\/div>\n            <\/div>\n        <\/div>\n        <\/a>\n    <\/div>\n    <div class=\"col-lg-4 col-md-6 col-12 couven-grid-item couven-teaser\">\n        <a href=\"https:\/\/couven-museum.de\/fr\/musee\/salon-vert\/\">\n        <div class=\"inner\">\n            <div class=\"grid-item-image\" style=\"background-image: url(https:\/\/couven-museum.de\/wp-content\/uploads\/2026\/03\/Gruener-Salon_MG_2259-ps1458_teaser-460x350.jpg)\">\n            <\/div>\n\n            <div class=\"grid-item-content\">\n                <h3>Salon vert<\/h3>\n                <div>On acc\u00e8de au Salon vert par deux magnifiques passages aux encadrements courbes de style rococo. Il servait de salon de r\u00e9ception repr\u00e9sentatif, mais \u00e9tait aussi un lieu de rencontre pour des r\u00e9unions conviviales.<\/div>\n            <\/div>\n        <\/div>\n        <\/a>\n    <\/div>\n    <div class=\"col-lg-4 col-md-6 col-12 couven-grid-item couven-teaser\">\n        <a href=\"https:\/\/couven-museum.de\/fr\/musee\/pharmacie\/\">\n        <div class=\"inner\">\n            <div class=\"grid-item-image\" style=\"background-image: url(https:\/\/couven-museum.de\/wp-content\/uploads\/2026\/03\/couven-museum-adler-apotheke-460x363.jpg)\">\n            <\/div>\n\n            <div class=\"grid-item-content\">\n                <h3>Pharmacie<\/h3>\n                <div>L\u2019Adler-Apotheke fut dirig\u00e9e par la famille Coebergh \u00e0 partir de 1662. En 1783, Andreas Monheim reprit l\u2019\u00e9tablissement. Il chargea Jakob Couven de r\u00e9am\u00e9nager la maison d\u2019habitation et de commerce, qui resta dans la famille jusqu\u2019en 1939.<\/div>\n            <\/div>\n        <\/div>\n        <\/a>\n    <\/div>\n    <div class=\"col-lg-4 col-md-6 col-12 couven-grid-item couven-teaser\">\n        <a href=\"https:\/\/couven-museum.de\/fr\/musee\/salon-empire\/\">\n        <div class=\"inner\">\n            <div class=\"grid-item-image\" style=\"background-image: url(https:\/\/couven-museum.de\/wp-content\/uploads\/2026\/03\/Empirezimmer_MG_2292-ps1475_teaser-460x307.jpg)\">\n            <\/div>\n\n            <div class=\"grid-item-content\">\n                <h3>Salon Empire<\/h3>\n                <div>Dans la salle Empire se trouve un mobilier au style classique rigoureux du d\u00e9but du XIXe si\u00e8cle, qui se diffusa dans toute l\u2019Europe sous l\u2019influence de l\u2019empereur Napol\u00e9on. Les lignes droites et les angles droits caract\u00e9risent ce style et remplac\u00e8rent les ornements sculpt\u00e9s (style Aix-la-Chapelle\u2013Li\u00e8ge).<\/div>\n            <\/div>\n        <\/div>\n        <\/a>\n    <\/div>\n    <div class=\"col-lg-4 col-md-6 col-12 couven-grid-item couven-teaser\">\n        <a href=\"https:\/\/couven-museum.de\/fr\/musee\/salon-directoire\/\">\n        <div class=\"inner\">\n            <div class=\"grid-item-image\" style=\"background-image: url(https:\/\/couven-museum.de\/wp-content\/uploads\/2026\/03\/Directoirezimmer_MG_2317-ps1469_teaser-460x351.jpg)\">\n            <\/div>\n\n            <div class=\"grid-item-content\">\n                <h3>Salon Directoire<\/h3>\n                <div>Entre 1795 et 1799, le Directoire gouverna la France r\u00e9volutionnaire, et donna son nom \u00e0 un style sp\u00e9cifique de mobilier et de mode : le \u00ab Directoire \u00bb. Ce style se caract\u00e9rise par un int\u00e9r\u00eat marqu\u00e9 pour l\u2019Antiquit\u00e9 gr\u00e9co-romaine, consid\u00e9r\u00e9e comme un mod\u00e8le de culture d\u00e9mocratique.<\/div>\n            <\/div>\n        <\/div>\n        <\/a>\n    <\/div>\n    <div class=\"col-lg-4 col-md-6 col-12 couven-grid-item couven-teaser\">\n        <a href=\"https:\/\/couven-museum.de\/fr\/musee\/salle-des-fetes\/\">\n        <div class=\"inner\">\n            <div class=\"grid-item-image\" style=\"background-image: url(https:\/\/couven-museum.de\/wp-content\/uploads\/2026\/03\/Festsaal_MG_2219_teaser-460x307.jpg)\">\n            <\/div>\n\n            <div class=\"grid-item-content\">\n                <h3>Salle des f\u00eates<\/h3>\n                <div>La salle des f\u00eates s\u2019inspire de l\u2019architecture palatiale des r\u00e9sidences princi\u00e8res et exprime l\u2019affirmation croissante de la bourgeoisie \u00e0 la fin du XVIIIe si\u00e8cle. Elle servait d\u2019espace de repr\u00e9sentation, o\u00f9 avaient lieu des concerts de musique de chambre, des r\u00e9ceptions et des f\u00eates, mais o\u00f9 l\u2019on concluait \u00e9galement d\u2019importants contrats.<\/div>\n            <\/div>\n        <\/div>\n        <\/a>\n    <\/div>\n    <div class=\"col-lg-4 col-md-6 col-12 couven-grid-item couven-teaser\">\n        <a href=\"https:\/\/couven-museum.de\/fr\/musee\/cuisine\/\">\n        <div class=\"inner\">\n            <div class=\"grid-item-image\" style=\"background-image: url(https:\/\/couven-museum.de\/wp-content\/uploads\/2026\/03\/Kueche_Teaser-460x307.png)\">\n            <\/div>\n\n            <div class=\"grid-item-content\">\n                <h3>Cuisine<\/h3>\n                <div>L\u2019am\u00e9nagement de la cuisine illustre les progr\u00e8s techniques des XVIIIe et XIXe si\u00e8cles. Le moulin \u00e0 caf\u00e9 et le torr\u00e9facteur rappellent les boissons de luxe de l\u2019\u00e9poque : le caf\u00e9, le th\u00e9 et le chocolat ont fait leur entr\u00e9e dans le milieu bourgeois au XVIIIe si\u00e8cle.<\/div>\n            <\/div>\n        <\/div>\n        <\/a>\n    <\/div>\n    <div class=\"col-lg-4 col-md-6 col-12 couven-grid-item couven-teaser\">\n        <a href=\"https:\/\/couven-museum.de\/fr\/musee\/salle-aux-carreaux\/\">\n        <div class=\"inner\">\n            <div class=\"grid-item-image\" style=\"background-image: url(https:\/\/couven-museum.de\/wp-content\/uploads\/2026\/03\/fliesenzimmer-couven-museum-460x363.jpg)\">\n            <\/div>\n\n            <div class=\"grid-item-content\">\n                <h3>Salle aux carreaux<\/h3>\n                <div>Les deux pi\u00e8ces de la maison \u00ab Zum Lindenbaum \u00bb ne font partie du mus\u00e9e que depuis 1961. Auparavant, ce b\u00e2timent \u00e9tait une maison d\u2019habitation ind\u00e9pendante. Aujourd\u2019hui, on peut y admirer quelque 6 000 carreaux de fa\u00efence provenant de la collection des collectionneurs aixois Peter et Irene Ludwig.<\/div>\n            <\/div>\n        <\/div>\n        <\/a>\n    <\/div>\n    <div class=\"col-lg-4 col-md-6 col-12 couven-grid-item couven-teaser\">\n        <a href=\"https:\/\/couven-museum.de\/fr\/musee\/1663-2\/\">\n        <div class=\"inner\">\n            <div class=\"grid-item-image\" style=\"background-image: url(https:\/\/couven-museum.de\/wp-content\/uploads\/2026\/03\/couven-museum-biedermeier-460x363.jpg)\">\n            <\/div>\n\n            <div class=\"grid-item-content\">\n                <h3>Biedermeier<\/h3>\n                <div>\u00c0 l\u2019\u00e9poque du Biedermeier, un art de vivre s\u2019est d\u00e9velopp\u00e9 qui pla\u00e7ait au centre le foyer confortable et chaleureux. La simplicit\u00e9 et la fonctionnalit\u00e9 d\u00e9terminaient le style de l\u2019am\u00e9nagement int\u00e9rieur.<\/div>\n            <\/div>\n        <\/div>\n        <\/a>\n    <\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-67ff71fd elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"67ff71fd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3ac45867\" data-id=\"3ac45867\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6158a514 elementor-widget elementor-widget-menu-anchor\" data-id=\"6158a514\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"restaurierung\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29f096dc elementor-widget elementor-widget-heading\" data-id=\"29f096dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">APPEL<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-73ea230d elementor-reverse-mobile elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"73ea230d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-613c1d2d\" data-id=\"613c1d2d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7dab25cb elementor-widget elementor-widget-text-editor\" data-id=\"7dab25cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-8912\" src=\"https:\/\/couven-museum.de\/wp-content\/uploads\/2022\/06\/Bastine_Familie_Blees_1828-460x317.jpg\" alt=\"\" width=\"460\" height=\"317\" srcset=\"https:\/\/couven-museum.de\/wp-content\/uploads\/2022\/06\/Bastine_Familie_Blees_1828-460x317.jpg 460w, https:\/\/couven-museum.de\/wp-content\/uploads\/2022\/06\/Bastine_Familie_Blees_1828-700x483.jpg 700w, https:\/\/couven-museum.de\/wp-content\/uploads\/2022\/06\/Bastine_Familie_Blees_1828-220x152.jpg 220w, https:\/\/couven-museum.de\/wp-content\/uploads\/2022\/06\/Bastine_Familie_Blees_1828.jpg 750w\" sizes=\"(max-width: 460px) 100vw, 460px\" \/>       Qui conna\u00eet ce tableau ?<\/h3>\n<p><\/p>\n<p>Comme aucun autre artiste de son \u00e9poque, Johann Baptist Joseph Bastin\u00e9 (1783\u20131844) a marqu\u00e9, par ses portraits des \u00e9lites urbaines, l\u2019image du Biedermeier aixois. Une \u0153uvre majeure du peintre, longtemps consid\u00e9r\u00e9e comme perdue, \u00e9tait le portrait de groupe grandeur nature \u00ab La famille Blees \u00bb de 1828, mesurant 1,48 x 2,40 m\u00e8tre, qui montre le fabricant de draps Richard Jakob Blees et son \u00e9pouse Anna Maria, n\u00e9e Bienbar, entour\u00e9s de leurs 14 (!) enfants. Des lettres ont r\u00e9cemment refait surface, prouvant qu\u2019apr\u00e8s la mort du dernier propri\u00e9taire connu, Berthold Theodor Thon (d\u00e9c\u00e9d\u00e9 en 1940 \u00e0 Potsdam), le tableau est retourn\u00e9 dans la branche rh\u00e9nane de la famille. Vers 1970, il se trouvait en possession de l\u2019arri\u00e8re-arri\u00e8re-petite-fille de Blees, Eva-Maria Lang, n\u00e9e Gei\u00dfeler (*1905), qui vivait \u00e0 Neuss-Weckhoven et \u00e9tait l\u2019\u00e9pouse du Dr m\u00e9d. Klaus Lang. \u00c0 l\u2019initiative de l\u2019historien de l\u2019art Dr Wolfgang Cortjaens (Deutsches Historisches Museum, Berlin), qui travaille actuellement \u00e0 un catalogue raisonn\u00e9 du peintre, le Couven Museum publie cet avis de recherche inhabituel et sera reconnaissant pour toute piste pouvant conduire \u00e0 la red\u00e9couverte du tableau. Toutes les informations re\u00e7ues seront trait\u00e9es dans la plus stricte confidentialit\u00e9. Bien entendu, les indications concernant d\u2019autres \u0153uvres de Bastin\u00e9 \u00e9ventuellement conserv\u00e9es dans des collections priv\u00e9es sont \u00e9galement les bienvenues !<br \/>Merci d\u2019adresser vos informations \u00e0 l\u2019adresse e-mail suivante : info@couven-museum.de<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1a411d37 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1a411d37\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4510176\" data-id=\"4510176\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-24c2759b elementor-widget elementor-widget-heading\" data-id=\"24c2759b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">BOUTIQUE DU MUS\u00c9E<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2762568f elementor-widget elementor-widget-text-editor\" data-id=\"2762568f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5>Dans notre boutique du mus\u00e9e, vous pouvez acheter les guides du mus\u00e9e de diff\u00e9rentes ann\u00e9es<br \/>ainsi que les catalogues des expositions en cours.<br \/>N\u2019h\u00e9sitez pas \u00e0 vous adresser \u00e0 notre personnel de caisse !<\/h5>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5f18e524 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5f18e524\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7ba77e5a\" data-id=\"7ba77e5a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-384e7147 elementor-widget elementor-widget-image\" data-id=\"384e7147\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"700\" height=\"609\" src=\"https:\/\/couven-museum.de\/wp-content\/uploads\/2019\/10\/couven_fuehrer2-700x609.jpg\" class=\"attachment-large size-large wp-image-11891\" alt=\"\" srcset=\"https:\/\/couven-museum.de\/wp-content\/uploads\/2019\/10\/couven_fuehrer2-700x609.jpg 700w, https:\/\/couven-museum.de\/wp-content\/uploads\/2019\/10\/couven_fuehrer2-220x191.jpg 220w, https:\/\/couven-museum.de\/wp-content\/uploads\/2019\/10\/couven_fuehrer2-460x400.jpg 460w, https:\/\/couven-museum.de\/wp-content\/uploads\/2019\/10\/couven_fuehrer2-768x668.jpg 768w, https:\/\/couven-museum.de\/wp-content\/uploads\/2019\/10\/couven_fuehrer2.jpg 920w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-293c094b elementor-widget elementor-widget-text-editor\" data-id=\"293c094b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Guide du mus\u00e9e (1986)<\/h3>\n<p><\/p>\n<p><strong>3,10 euros<\/strong><br \/><strong>Mus\u00e9es de la ville d\u2019Aix-la-Chapelle, 1986. 4e \u00e9dition, illustrations en partie en couleur, 82 pages<\/strong><\/p>\n<p><\/p>\n<p>L\u2019ancien directeur du mus\u00e9e, Ernst G\u00fcnther Grimme, propose une introduction \u00e0 Johann Joseph Couven et au \u00ab rococo aixois \u00bb, d\u00e9crit l\u2019am\u00e9nagement des salles et consacre un chapitre entier aux nombreuses horloges du Couven Museum (1re \u00e9dition en 1971).<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-248f3bed\" data-id=\"248f3bed\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-658192c elementor-widget elementor-widget-image\" data-id=\"658192c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"700\" height=\"609\" src=\"https:\/\/couven-museum.de\/wp-content\/uploads\/2019\/10\/couven_fuehrer-700x609.jpg\" class=\"attachment-large size-large wp-image-11890\" alt=\"\" srcset=\"https:\/\/couven-museum.de\/wp-content\/uploads\/2019\/10\/couven_fuehrer-700x609.jpg 700w, https:\/\/couven-museum.de\/wp-content\/uploads\/2019\/10\/couven_fuehrer-220x191.jpg 220w, https:\/\/couven-museum.de\/wp-content\/uploads\/2019\/10\/couven_fuehrer-460x400.jpg 460w, https:\/\/couven-museum.de\/wp-content\/uploads\/2019\/10\/couven_fuehrer-768x668.jpg 768w, https:\/\/couven-museum.de\/wp-content\/uploads\/2019\/10\/couven_fuehrer.jpg 920w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2deb90bb elementor-widget elementor-widget-text-editor\" data-id=\"2deb90bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Guide du mus\u00e9e (2010)<\/h3>\n<p><\/p>\n<p><strong>7 euros<br \/>Deutscher Kunstverlag, Berlin \/ Munich ; \u00e9dit\u00e9 par Dagmar Preising et Ulrich Sch\u00e4fer, 2010. Illustrations en couleur, 78 pages<br \/><\/strong><\/p>\n<p><\/p>\n<p>Une visite vivante des \u00ab period rooms \u00bb de la maison, pr\u00e9sentant des ensembles de meubles, chemin\u00e9es, peintures, porcelaine et argenterie ; disponible en allemand, en anglais, en fran\u00e7ais et en n\u00e9erlandais.<\/p>\n<p><\/p>\n<p>La Fondation Peter et Irene Ludwig ainsi que le Landschaftsverband Rheinland ont rendu cette publication possible.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3b5ef51c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3b5ef51c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-35c6bbd4\" data-id=\"35c6bbd4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-61200e6a elementor-widget elementor-widget-heading\" data-id=\"61200e6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Location<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-902f956 elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"902f956\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-423fff3\" data-id=\"423fff3\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e43c99 elementor-widget elementor-widget-text-editor\" data-id=\"1e43c99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Une ambiance festive<\/h3>\n<p><\/p>\n<p class=\"p1\"><b>Le Couven Museum peut \u00eatre lou\u00e9 pour des mariages <\/b><b>et d\u2019autres c\u00e9l\u00e9brations<\/b><\/p>\n<p><\/p>\n<p><span class=\"s1\">Vous pouvez obtenir toutes les informations sur la location <\/span><span class=\"s1\">par t\u00e9l\u00e9phone au +49 241 432-4999.<\/span><\/p>\n<p><\/p>\n<p class=\"p1\"><span class=\"s1\">Les couples qui souhaitent se marier dans un cadre historique <\/span><span class=\"s1\">peuvent se dire oui dans la salle des f\u00eates <\/span><span class=\"s1\">du Couven Museum. <\/span><span class=\"s1\">Vous pouvez joindre vos interlocuteur*trice*s \u00e0 l\u2019\u00e9tat civil au <\/span><span class=\"s1\">+49 241 432-3409.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8906cda elementor-widget elementor-widget-button\" data-id=\"8906cda\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.locations-aachen.de\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">LOCATIONS-AACHEN.DE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-3021254\" data-id=\"3021254\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f04a37 elementor-widget elementor-widget-spacer\" data-id=\"2f04a37\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e2a378f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e2a378f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-87ef03c\" data-id=\"87ef03c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ad46579 elementor-widget elementor-widget-heading\" data-id=\"ad46579\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">En savoir plus sur le mus\u00e9e<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8b6aa7b text-white elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8b6aa7b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7aaf925\" data-id=\"7aaf925\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a3aadb white-text elementor-widget elementor-widget-heading\" data-id=\"2a3aadb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">SOUTENIR LE MUS\u00c9E<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73c7d04 elementor-widget elementor-widget-text-editor\" data-id=\"73c7d04\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Das Couven Museum bietet viele M\u00f6glichkeiten, sich einzubringen<\/strong><\/p>\n<p>Wir brauchen Ihr Interesse, Ihre Arbeitskraft und gerne auch Ihre finanzielle Unterst\u00fctzung. Auch besteht die M\u00f6glichkeit, Mitglied im Museumsverein Aachen zu werden.<\/p>\n<p>Tel.: + 49 241 432 4956 (Mo \u2013 Fr 9 \u2013 14 Uhr)<br \/>info@couven-museum.de<\/p>\n<p><strong>Spendenkonten<\/strong><br \/>Museumsverein Aachen<br \/>Sparkasse Aachen<br \/>IBAN DE30 3905 0000 0006 0055 08<br \/>Deutsche Bank<br \/>IBAN DE39 3907 0020 0151 5741 00<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11c3c89 elementor-widget elementor-widget-button\" data-id=\"11c3c89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"http:\/\/www.museumsverein-aachen.de\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">EN SAVOIR PLUS SUR L\u2019ASSOCIATION DES MUS\u00c9ES<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-23b6ba8\" data-id=\"23b6ba8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ab5bef white-text elementor-widget elementor-widget-heading\" data-id=\"4ab5bef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">MERCI \u00c0 NOS SPONSORS<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8d4db9c elementor-widget elementor-widget-text-editor\" data-id=\"8d4db9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: bolder\">De nombreux sponsors soutiennent <\/span><span style=\"font-weight: bolder\">le Couven Museum<\/span><\/p>\n<p><\/p>\n<p>Le guide du mus\u00e9e paru en 2010 a \u00e9t\u00e9 financ\u00e9 par la Fondation Peter &amp; Irene Ludwig ainsi que par le Landschaftsverband Rheinland.<\/p>\n<p><\/p>\n<p>L\u2019Association des mus\u00e9es a soutenu l\u2019acquisition du tableau \u00ab La famille du conseiller de chancellerie Janssen \u00bb de Clemens Bewer, datant de 1843. L\u2019Association des mus\u00e9es et la Sparkasse Aachen ont financ\u00e9 l\u2019acquisition d\u2019un tableau d\u2019int\u00e9rieur de Hans Schaffrath, datant des ann\u00e9es 1930, qui repr\u00e9sente une salle de l\u2019ancien Couven Museum, d\u00e9truit pendant la guerre, situ\u00e9 au Seilgraben.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2616fdd\" data-id=\"2616fdd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-000808f elementor-widget elementor-widget-text-editor\" data-id=\"000808f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le Landschaftsverband Rheinland a soutenu les expositions \u00ab Le d\u00e9senchantement de l\u2019Occident. Le caf\u00e9 et le th\u00e9 \u00e0 la conqu\u00eate de l\u2019Europe \u00bb (2010\/11) et \u00ab L\u2019Enfant J\u00e9sus sous vitrine de verre. De la magie des ouvrages conventuels baroques \u00bb (2011\/12). Lindt a soutenu l\u2019exposition \u00ab Douce tentation. Du cacao au chocolat \u00bb (2009), <span class=\"Apple-converted-space\" style=\"font-size: 1rem\">  <\/span><span style=\"font-size: 1rem\">Stawag l\u2019exposition \u00ab Bien au chaud. La culture du chauffage entre Renaissance et \u00e9poque imp\u00e9riale \u00bb (2009\/10), Babor l\u2019exposition \u00ab La Beaut\u00e9. Histoire de la cosm\u00e9tique \u00bb (2011). La Fondation Peter &amp; Irene Ludwig a financ\u00e9 le catalogue de l\u2019exposition \u00ab Vie int\u00e9rieure. Wolfgang Nestler \u2013 Un projet artistique \u00bb.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>LA MAISON De la maison Coebergh au mus\u00e9e d\u2019aujourd\u2019hui L\u2019art de vivre aux XVIIIe et XIXe si\u00e8cles \u00c0 partir de 1662, le pharmacien Adam Coebergh fit construire la maison situ\u00e9e [&hellip;]<\/p>\n","protected":false},"author":45,"featured_media":11889,"parent":0,"menu_order":13,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[],"tags":[],"class_list":["post-11880","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mus\u00e9e - Couven Museum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/couven-museum.de\/museum\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mus\u00e9e - Couven Museum\" \/>\n<meta property=\"og:description\" content=\"LA MAISON De la maison Coebergh au mus\u00e9e d\u2019aujourd\u2019hui L\u2019art de vivre aux XVIIIe et XIXe si\u00e8cles \u00c0 partir de 1662, le pharmacien Adam Coebergh fit construire la maison situ\u00e9e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/couven-museum.de\/museum\/\" \/>\n<meta property=\"og:site_name\" content=\"Couven Museum\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-28T17:42:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/couven-museum.de\/wp-content\/uploads\/2019\/10\/header-couven-mueseum-apotheke.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"410\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/couven-museum.de\\\/museum\\\/\",\"url\":\"https:\\\/\\\/couven-museum.de\\\/museum\\\/\",\"name\":\"Mus\u00e9e - Couven Museum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/couven-museum.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/couven-museum.de\\\/museum\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/couven-museum.de\\\/museum\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/couven-museum.de\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/header-couven-mueseum-apotheke.jpg\",\"datePublished\":\"2019-09-05T14:45:10+00:00\",\"dateModified\":\"2026-03-28T17:42:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/couven-museum.de\\\/museum\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/couven-museum.de\\\/museum\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/couven-museum.de\\\/museum\\\/#primaryimage\",\"url\":\"https:\\\/\\\/couven-museum.de\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/header-couven-mueseum-apotheke.jpg\",\"contentUrl\":\"https:\\\/\\\/couven-museum.de\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/header-couven-mueseum-apotheke.jpg\",\"width\":1920,\"height\":410},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/couven-museum.de\\\/museum\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/couven-museum.de\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mus\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/couven-museum.de\\\/#website\",\"url\":\"https:\\\/\\\/couven-museum.de\\\/\",\"name\":\"Couven Museum\",\"description\":\"Couven-Museum Aachen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/couven-museum.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mus\u00e9e - Couven Museum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/couven-museum.de\/museum\/","og_locale":"fr_FR","og_type":"article","og_title":"Mus\u00e9e - Couven Museum","og_description":"LA MAISON De la maison Coebergh au mus\u00e9e d\u2019aujourd\u2019hui L\u2019art de vivre aux XVIIIe et XIXe si\u00e8cles \u00c0 partir de 1662, le pharmacien Adam Coebergh fit construire la maison situ\u00e9e [&hellip;]","og_url":"https:\/\/couven-museum.de\/museum\/","og_site_name":"Couven Museum","article_modified_time":"2026-03-28T17:42:26+00:00","og_image":[{"width":1920,"height":410,"url":"https:\/\/couven-museum.de\/wp-content\/uploads\/2019\/10\/header-couven-mueseum-apotheke.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/couven-museum.de\/museum\/","url":"https:\/\/couven-museum.de\/museum\/","name":"Mus\u00e9e - Couven Museum","isPartOf":{"@id":"https:\/\/couven-museum.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/couven-museum.de\/museum\/#primaryimage"},"image":{"@id":"https:\/\/couven-museum.de\/museum\/#primaryimage"},"thumbnailUrl":"https:\/\/couven-museum.de\/wp-content\/uploads\/2019\/10\/header-couven-mueseum-apotheke.jpg","datePublished":"2019-09-05T14:45:10+00:00","dateModified":"2026-03-28T17:42:26+00:00","breadcrumb":{"@id":"https:\/\/couven-museum.de\/museum\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/couven-museum.de\/museum\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/couven-museum.de\/museum\/#primaryimage","url":"https:\/\/couven-museum.de\/wp-content\/uploads\/2019\/10\/header-couven-mueseum-apotheke.jpg","contentUrl":"https:\/\/couven-museum.de\/wp-content\/uploads\/2019\/10\/header-couven-mueseum-apotheke.jpg","width":1920,"height":410},{"@type":"BreadcrumbList","@id":"https:\/\/couven-museum.de\/museum\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/couven-museum.de\/fr\/"},{"@type":"ListItem","position":2,"name":"Mus\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/couven-museum.de\/#website","url":"https:\/\/couven-museum.de\/","name":"Couven Museum","description":"Couven-Museum Aachen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/couven-museum.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/couven-museum.de\/fr\/wp-json\/wp\/v2\/pages\/11880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/couven-museum.de\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/couven-museum.de\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/couven-museum.de\/fr\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/couven-museum.de\/fr\/wp-json\/wp\/v2\/comments?post=11880"}],"version-history":[{"count":1,"href":"https:\/\/couven-museum.de\/fr\/wp-json\/wp\/v2\/pages\/11880\/revisions"}],"predecessor-version":[{"id":11894,"href":"https:\/\/couven-museum.de\/fr\/wp-json\/wp\/v2\/pages\/11880\/revisions\/11894"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/couven-museum.de\/fr\/wp-json\/wp\/v2\/media\/11889"}],"wp:attachment":[{"href":"https:\/\/couven-museum.de\/fr\/wp-json\/wp\/v2\/media?parent=11880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/couven-museum.de\/fr\/wp-json\/wp\/v2\/categories?post=11880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/couven-museum.de\/fr\/wp-json\/wp\/v2\/tags?post=11880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}