{"id":2904,"date":"2013-08-28T11:39:53","date_gmt":"2013-08-28T09:39:53","guid":{"rendered":"http:\/\/couven-museum.de\/?post_type=tribe_events&#038;p=2904"},"modified":"2013-12-23T18:37:43","modified_gmt":"2013-12-23T17:37:43","slug":"uppige-pracht-und-intime-poesie-4","status":"publish","type":"tribe_events","link":"https:\/\/couven-museum.de\/fr\/event\/uppige-pracht-und-intime-poesie-4\/","title":{"rendered":"\u00dcppige Pracht und intime Poesie"},"content":{"rendered":"<p>Studierende der Gesangsklasse von Prof. Claudia Kunz-Eisenlohr und der Gitarrenklasse von Prof. Hans-Werner Huppertz interpretieren Werke aus Barock und Fr\u00fchromantik.<\/p>\n<p>In Kooperation mit der Hochschule f\u00fcr Musik und Tanz K\u00f6ln\/ Aachen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Konzert mit Studierenden der Hochschule f\u00fcr Musik und Tanz<br \/>\nIm Rahmen von &#8220;Klangwelten in Couven-R\u00e4umen&#8221;<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_lmt_disableupdate":"","_lmt_disable":"","_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[15],"class_list":["post-2904","tribe_events","type-tribe_events","status-publish","hentry","tribe_events_cat-veranstaltungen-fr","cat_veranstaltungen-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00dcppige Pracht und intime Poesie - Couven Museum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/couven-museum.de\/fr\/event\/uppige-pracht-und-intime-poesie-4\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00dcppige Pracht und intime Poesie - Couven Museum\" \/>\n<meta property=\"og:description\" content=\"Konzert mit Studierenden der Hochschule f\u00fcr Musik und Tanz Im Rahmen von &quot;Klangwelten in Couven-R\u00e4umen&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/couven-museum.de\/fr\/event\/uppige-pracht-und-intime-poesie-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Couven Museum\" \/>\n<meta property=\"article:modified_time\" content=\"2013-12-23T17:37:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/couven-museum.de\\\/fr\\\/event\\\/uppige-pracht-und-intime-poesie-4\\\/\",\"url\":\"https:\\\/\\\/couven-museum.de\\\/fr\\\/event\\\/uppige-pracht-und-intime-poesie-4\\\/\",\"name\":\"\u00dcppige Pracht und intime Poesie - Couven Museum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/couven-museum.de\\\/#website\"},\"datePublished\":\"2013-08-28T09:39:53+00:00\",\"dateModified\":\"2013-12-23T17:37:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/couven-museum.de\\\/fr\\\/event\\\/uppige-pracht-und-intime-poesie-4\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/couven-museum.de\\\/fr\\\/event\\\/uppige-pracht-und-intime-poesie-4\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/couven-museum.de\\\/fr\\\/event\\\/uppige-pracht-und-intime-poesie-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/couven-museum.de\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/couven-museum.de\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00dcppige Pracht und intime Poesie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/couven-museum.de\\\/#website\",\"url\":\"https:\\\/\\\/couven-museum.de\\\/\",\"name\":\"Couven Museum\",\"description\":\"Couven-Museum Aachen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/couven-museum.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00dcppige Pracht und intime Poesie - Couven Museum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/couven-museum.de\/fr\/event\/uppige-pracht-und-intime-poesie-4\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00dcppige Pracht und intime Poesie - Couven Museum","og_description":"Konzert mit Studierenden der Hochschule f\u00fcr Musik und Tanz Im Rahmen von \"Klangwelten in Couven-R\u00e4umen\"","og_url":"https:\/\/couven-museum.de\/fr\/event\/uppige-pracht-und-intime-poesie-4\/","og_site_name":"Couven Museum","article_modified_time":"2013-12-23T17:37:43+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/couven-museum.de\/fr\/event\/uppige-pracht-und-intime-poesie-4\/","url":"https:\/\/couven-museum.de\/fr\/event\/uppige-pracht-und-intime-poesie-4\/","name":"\u00dcppige Pracht und intime Poesie - Couven Museum","isPartOf":{"@id":"https:\/\/couven-museum.de\/#website"},"datePublished":"2013-08-28T09:39:53+00:00","dateModified":"2013-12-23T17:37:43+00:00","breadcrumb":{"@id":"https:\/\/couven-museum.de\/fr\/event\/uppige-pracht-und-intime-poesie-4\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/couven-museum.de\/fr\/event\/uppige-pracht-und-intime-poesie-4\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/couven-museum.de\/fr\/event\/uppige-pracht-und-intime-poesie-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/couven-museum.de\/fr\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/couven-museum.de\/events\/"},{"@type":"ListItem","position":3,"name":"\u00dcppige Pracht und intime Poesie"}]},{"@type":"WebSite","@id":"https:\/\/couven-museum.de\/#website","url":"https:\/\/couven-museum.de\/","name":"Couven Museum","description":"Couven-Museum Aachen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/couven-museum.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/couven-museum.de\/fr\/wp-json\/wp\/v2\/tribe_events\/2904","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/couven-museum.de\/fr\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/couven-museum.de\/fr\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/couven-museum.de\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/couven-museum.de\/fr\/wp-json\/wp\/v2\/tribe_events\/2904\/revisions"}],"wp:attachment":[{"href":"https:\/\/couven-museum.de\/fr\/wp-json\/wp\/v2\/media?parent=2904"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/couven-museum.de\/fr\/wp-json\/wp\/v2\/tags?post=2904"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/couven-museum.de\/fr\/wp-json\/wp\/v2\/tribe_events_cat?post=2904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}